{"id":3765,"date":"2019-12-16T13:00:45","date_gmt":"2019-12-16T11:00:45","guid":{"rendered":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107.jpg"},"modified":"2019-12-16T13:01:18","modified_gmt":"2019-12-16T11:01:18","slug":"dsc02107","status":"inherit","type":"attachment","link":"https:\/\/ev-luth-gemeinde-rom.org\/it\/dsc02107\/","title":{"rendered":"DSC02107"},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3765","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107.jpg' rel=\"lightbox[3765]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-300x200.jpg 300w, https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-768x511.jpg 768w, https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-1024x681.jpg 1024w, https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-550x366.jpg 550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4592,"height":3056,"file":"2019\/12\/DSC02107.jpg","sizes":{"thumbnail":{"file":"DSC02107-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-150x150.jpg"},"medium":{"file":"DSC02107-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-300x200.jpg"},"medium_large":{"file":"DSC02107-768x511.jpg","width":768,"height":511,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-768x511.jpg"},"large":{"file":"DSC02107-1024x681.jpg","width":1024,"height":681,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-1024x681.jpg"},"post-thumbnail":{"file":"DSC02107-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-100x100.jpg"},"inpost":{"file":"DSC02107-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-280x280.jpg"},"lightbox":{"file":"DSC02107-550x366.jpg","width":550,"height":366,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-550x366.jpg"},"featured-blog-large":{"file":"DSC02107-750x350.jpg","width":750,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-750x350.jpg"},"featured-blog-medium":{"file":"DSC02107-270x270.jpg","width":270,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-270x270.jpg"},"featured":{"file":"DSC02107-642x300.jpg","width":642,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-642x300.jpg"},"featured-blog-medium-small":{"file":"DSC02107-230x230.jpg","width":230,"height":230,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107-230x230.jpg"},"full":{"file":"DSC02107.jpg","width":4592,"height":3056,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2019\/12\/DSC02107.jpg","filename":"DSC02107.jpg","filesize":5275648,"_links":{"self":[{"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/media\/3765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/comments?post=3765"}]}}