{"id":2607,"date":"2017-10-23T10:46:51","date_gmt":"2017-10-23T08:46:51","guid":{"rendered":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8.jpg"},"modified":"2017-10-23T10:54:47","modified_gmt":"2017-10-23T08:54:47","slug":"bpr-8","status":"inherit","type":"attachment","link":"https:\/\/ev-luth-gemeinde-rom.org\/it\/bpr-8\/","title":{"rendered":"BPR 8"},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-2607","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8.jpg' rel=\"lightbox[2607]\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-200x300.jpg 200w, https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-768x1152.jpg 768w, https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-683x1024.jpg 683w, https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-367x550.jpg 367w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2592,"height":3888,"file":"2017\/10\/BPR-8.jpg","sizes":{"thumbnail":{"file":"BPR-8-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-150x150.jpg"},"medium":{"file":"BPR-8-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-200x300.jpg"},"medium_large":{"file":"BPR-8-768x1152.jpg","width":768,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-768x1152.jpg"},"large":{"file":"BPR-8-683x1024.jpg","width":683,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-683x1024.jpg"},"post-thumbnail":{"file":"BPR-8-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-100x100.jpg"},"inpost":{"file":"BPR-8-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-280x280.jpg"},"lightbox":{"file":"BPR-8-367x550.jpg","width":367,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-367x550.jpg"},"featured-blog-large":{"file":"BPR-8-750x350.jpg","width":750,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-750x350.jpg"},"featured-blog-medium":{"file":"BPR-8-270x270.jpg","width":270,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-270x270.jpg"},"featured":{"file":"BPR-8-642x300.jpg","width":642,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-642x300.jpg"},"featured-blog-medium-small":{"file":"BPR-8-230x230.jpg","width":230,"height":230,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8-230x230.jpg"},"full":{"file":"BPR-8.jpg","width":2592,"height":3888,"mime_type":"image\/jpeg","source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8.jpg"}},"image_meta":{"aperture":"5.6","credit":"","camera":"Canon EOS 40D","caption":"","created_timestamp":"1507490675","copyright":"","focal_length":"14","iso":"1250","shutter_speed":"0.16666666666667","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/ev-luth-gemeinde-rom.org\/wp-content\/uploads\/2017\/10\/BPR-8.jpg","filename":"BPR-8.jpg","filesize":8254756,"_links":{"self":[{"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/media\/2607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ev-luth-gemeinde-rom.org\/it\/wp-json\/wp\/v2\/comments?post=2607"}]}}